{"id":8524,"date":"2023-09-02T18:16:11","date_gmt":"2023-09-02T16:16:11","guid":{"rendered":"https:\/\/wallart.pl\/?p=8524"},"modified":"2025-01-10T21:02:59","modified_gmt":"2025-01-10T20:02:59","slug":"429-peinture-murale-nos-coquelicots-a-wroclaw","status":"publish","type":"post","link":"https:\/\/wallart.pl\/fr\/429-nasze-maki-mural-we-wroclawiu\/","title":{"rendered":"429 Nos coquelicots"},"content":{"rendered":"<p>[et_pb_section bb_built=&#8221;1&#8243; _builder_version=&#8221;3.22&#8243; custom_css_main_element=&#8221;margin-bottom: 0px !important;||padding-bottom: 5px !important;||margin-top: 0px !important;||padding-top: 10px !important;&#8221;][et_pb_row _builder_version=&#8221;4.5.3&#8243; custom_margin=&#8221;10px||0px&#8221; custom_margin_phone=&#8221;15px||&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;0px||0px&#8221; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; vertical_offset_tablet=&#8221;0&#8243; horizontal_offset_tablet=&#8221;0&#8243; z_index_tablet=&#8221;0&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.5.3&#8243; text_text_shadow_horizontal_length=&#8221;text_text_shadow_style,%91object Object%93&#8243; text_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; text_text_shadow_vertical_length=&#8221;text_text_shadow_style,%91object Object%93&#8243; text_text_shadow_vertical_length_tablet=&#8221;0px&#8221; text_text_shadow_blur_strength=&#8221;text_text_shadow_style,%91object Object%93&#8243; text_text_shadow_blur_strength_tablet=&#8221;1px&#8221; link_text_shadow_horizontal_length=&#8221;link_text_shadow_style,%91object Object%93&#8243; link_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; link_text_shadow_vertical_length=&#8221;link_text_shadow_style,%91object Object%93&#8243; link_text_shadow_vertical_length_tablet=&#8221;0px&#8221; link_text_shadow_blur_strength=&#8221;link_text_shadow_style,%91object Object%93&#8243; link_text_shadow_blur_strength_tablet=&#8221;1px&#8221; ul_text_shadow_horizontal_length=&#8221;ul_text_shadow_style,%91object Object%93&#8243; ul_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; ul_text_shadow_vertical_length=&#8221;ul_text_shadow_style,%91object Object%93&#8243; ul_text_shadow_vertical_length_tablet=&#8221;0px&#8221; ul_text_shadow_blur_strength=&#8221;ul_text_shadow_style,%91object Object%93&#8243; ul_text_shadow_blur_strength_tablet=&#8221;1px&#8221; ol_text_shadow_horizontal_length=&#8221;ol_text_shadow_style,%91object Object%93&#8243; ol_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; ol_text_shadow_vertical_length=&#8221;ol_text_shadow_style,%91object Object%93&#8243; ol_text_shadow_vertical_length_tablet=&#8221;0px&#8221; ol_text_shadow_blur_strength=&#8221;ol_text_shadow_style,%91object Object%93&#8243; ol_text_shadow_blur_strength_tablet=&#8221;1px&#8221; quote_text_shadow_horizontal_length=&#8221;quote_text_shadow_style,%91object Object%93&#8243; quote_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; quote_text_shadow_vertical_length=&#8221;quote_text_shadow_style,%91object Object%93&#8243; quote_text_shadow_vertical_length_tablet=&#8221;0px&#8221; quote_text_shadow_blur_strength=&#8221;quote_text_shadow_style,%91object Object%93&#8243; quote_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_text_shadow_horizontal_length=&#8221;header_text_shadow_style,%91object Object%93&#8243; header_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_text_shadow_vertical_length=&#8221;header_text_shadow_style,%91object Object%93&#8243; header_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_text_shadow_blur_strength=&#8221;header_text_shadow_style,%91object Object%93&#8243; header_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_2_text_shadow_horizontal_length=&#8221;header_2_text_shadow_style,%91object Object%93&#8243; header_2_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_2_text_shadow_vertical_length=&#8221;header_2_text_shadow_style,%91object Object%93&#8243; header_2_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_2_text_shadow_blur_strength=&#8221;header_2_text_shadow_style,%91object Object%93&#8243; header_2_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_3_text_shadow_horizontal_length=&#8221;header_3_text_shadow_style,%91object Object%93&#8243; header_3_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_3_text_shadow_vertical_length=&#8221;header_3_text_shadow_style,%91object Object%93&#8243; header_3_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_3_text_shadow_blur_strength=&#8221;header_3_text_shadow_style,%91object Object%93&#8243; header_3_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_4_text_shadow_horizontal_length=&#8221;header_4_text_shadow_style,%91object Object%93&#8243; header_4_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_4_text_shadow_vertical_length=&#8221;header_4_text_shadow_style,%91object Object%93&#8243; header_4_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_4_text_shadow_blur_strength=&#8221;header_4_text_shadow_style,%91object Object%93&#8243; header_4_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_5_text_shadow_horizontal_length=&#8221;header_5_text_shadow_style,%91object Object%93&#8243; header_5_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_5_text_shadow_vertical_length=&#8221;header_5_text_shadow_style,%91object Object%93&#8243; header_5_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_5_text_shadow_blur_strength=&#8221;header_5_text_shadow_style,%91object Object%93&#8243; header_5_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_6_text_shadow_horizontal_length=&#8221;header_6_text_shadow_style,%91object Object%93&#8243; header_6_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_6_text_shadow_vertical_length=&#8221;header_6_text_shadow_style,%91object Object%93&#8243; header_6_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_6_text_shadow_blur_strength=&#8221;header_6_text_shadow_style,%91object Object%93&#8243; header_6_text_shadow_blur_strength_tablet=&#8221;1px&#8221; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; vertical_offset_tablet=&#8221;0&#8243; horizontal_offset_tablet=&#8221;0&#8243; z_index_tablet=&#8221;0&#8243; custom_margin=&#8221;||20px|&#8221;]<\/p>\n<h3>Kampania muralowa<\/h3>\n<p>Jeden z wielu murali w ramach kampani muralowej Nasze Maki<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=&#8221;on|desktop&#8221; disabled_on=&#8221;off|off|off&#8221; module_class=&#8221;projekt-info&#8221; _builder_version=&#8221;4.5.3&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||0px|&#8221; custom_padding=&#8221;0%||0px||false|false&#8221; custom_padding_phone=&#8221;||0px&#8221; hover_enabled=&#8221;0&#8243; custom_css_main_element=&#8221;margin-bottom: 0px !important;||padding-bottom: 0px !important;||margin-top: 0px !important;||padding-top: 0px !important;&#8221; column_structure=&#8221;1_4,1_4,1_4,1_4&#8243;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Tekst_nr2&#8243; _builder_version=&#8221;4.5.3&#8243; text_font=&#8221;|300|||||||&#8221; text_orientation=&#8221;center&#8221; hover_enabled=&#8221;0&#8243; text_text_shadow_horizontal_length=&#8221;text_text_shadow_style,%91object Object%93&#8243; text_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; text_text_shadow_vertical_length=&#8221;text_text_shadow_style,%91object Object%93&#8243; text_text_shadow_vertical_length_tablet=&#8221;0px&#8221; text_text_shadow_blur_strength=&#8221;text_text_shadow_style,%91object Object%93&#8243; text_text_shadow_blur_strength_tablet=&#8221;1px&#8221; link_text_shadow_horizontal_length=&#8221;link_text_shadow_style,%91object Object%93&#8243; link_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; link_text_shadow_vertical_length=&#8221;link_text_shadow_style,%91object Object%93&#8243; link_text_shadow_vertical_length_tablet=&#8221;0px&#8221; link_text_shadow_blur_strength=&#8221;link_text_shadow_style,%91object Object%93&#8243; link_text_shadow_blur_strength_tablet=&#8221;1px&#8221; ul_text_shadow_horizontal_length=&#8221;ul_text_shadow_style,%91object Object%93&#8243; ul_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; ul_text_shadow_vertical_length=&#8221;ul_text_shadow_style,%91object Object%93&#8243; ul_text_shadow_vertical_length_tablet=&#8221;0px&#8221; ul_text_shadow_blur_strength=&#8221;ul_text_shadow_style,%91object Object%93&#8243; ul_text_shadow_blur_strength_tablet=&#8221;1px&#8221; ol_text_shadow_horizontal_length=&#8221;ol_text_shadow_style,%91object Object%93&#8243; ol_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; ol_text_shadow_vertical_length=&#8221;ol_text_shadow_style,%91object Object%93&#8243; ol_text_shadow_vertical_length_tablet=&#8221;0px&#8221; ol_text_shadow_blur_strength=&#8221;ol_text_shadow_style,%91object Object%93&#8243; ol_text_shadow_blur_strength_tablet=&#8221;1px&#8221; quote_text_shadow_horizontal_length=&#8221;quote_text_shadow_style,%91object Object%93&#8243; quote_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; quote_text_shadow_vertical_length=&#8221;quote_text_shadow_style,%91object Object%93&#8243; quote_text_shadow_vertical_length_tablet=&#8221;0px&#8221; quote_text_shadow_blur_strength=&#8221;quote_text_shadow_style,%91object Object%93&#8243; quote_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_text_shadow_horizontal_length=&#8221;header_text_shadow_style,%91object Object%93&#8243; header_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_text_shadow_vertical_length=&#8221;header_text_shadow_style,%91object Object%93&#8243; header_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_text_shadow_blur_strength=&#8221;header_text_shadow_style,%91object Object%93&#8243; header_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_2_text_shadow_horizontal_length=&#8221;header_2_text_shadow_style,%91object Object%93&#8243; header_2_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_2_text_shadow_vertical_length=&#8221;header_2_text_shadow_style,%91object Object%93&#8243; header_2_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_2_text_shadow_blur_strength=&#8221;header_2_text_shadow_style,%91object Object%93&#8243; header_2_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_3_text_shadow_horizontal_length=&#8221;header_3_text_shadow_style,%91object Object%93&#8243; header_3_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_3_text_shadow_vertical_length=&#8221;header_3_text_shadow_style,%91object Object%93&#8243; header_3_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_3_text_shadow_blur_strength=&#8221;header_3_text_shadow_style,%91object Object%93&#8243; header_3_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_4_text_shadow_horizontal_length=&#8221;header_4_text_shadow_style,%91object Object%93&#8243; header_4_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_4_text_shadow_vertical_length=&#8221;header_4_text_shadow_style,%91object Object%93&#8243; header_4_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_4_text_shadow_blur_strength=&#8221;header_4_text_shadow_style,%91object Object%93&#8243; header_4_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_5_text_shadow_horizontal_length=&#8221;header_5_text_shadow_style,%91object Object%93&#8243; header_5_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_5_text_shadow_vertical_length=&#8221;header_5_text_shadow_style,%91object Object%93&#8243; header_5_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_5_text_shadow_blur_strength=&#8221;header_5_text_shadow_style,%91object Object%93&#8243; header_5_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_6_text_shadow_horizontal_length=&#8221;header_6_text_shadow_style,%91object Object%93&#8243; header_6_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_6_text_shadow_vertical_length=&#8221;header_6_text_shadow_style,%91object Object%93&#8243; header_6_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_6_text_shadow_blur_strength=&#8221;header_6_text_shadow_style,%91object Object%93&#8243; header_6_text_shadow_blur_strength_tablet=&#8221;1px&#8221; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; vertical_offset_tablet=&#8221;0&#8243; horizontal_offset_tablet=&#8221;0&#8243; z_index_tablet=&#8221;0&#8243;]<\/p>\n<p>adres: Boya-\u017bele\u0144skiego 72, Wroc\u0142aw<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.25&#8243; custom_margin=&#8221;10px||0px&#8221; custom_margin_phone=&#8221;15px||&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;0px||0px&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_gallery admin_label=&#8221;Wy\u015bwietlane zdj\u0119cia&#8221; gallery_ids=&#8221;8527,8526&#8243; posts_number=&#8221;100&#8243; show_pagination=&#8221;off&#8221; zoom_icon_color=&#8221;#fbb011&#8243; hover_overlay_color=&#8221;rgba(255,255,255,0.65)&#8221; hover_icon=&#8221;%%51%%&#8221; module_class=&#8221;gallery2&#8243; _builder_version=&#8221;4.5.3&#8243; title_font=&#8221;Oswald|300|||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;20px&#8221; caption_font=&#8221;Oswald|300|||||||&#8221; caption_text_align=&#8221;center&#8221; caption_font_size=&#8221;20px&#8221; text_orientation=&#8221;center&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||&#8221; custom_margin_phone=&#8221;0px||0px&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;0px||0px&#8221; hover_enabled=&#8221;0&#8243; custom_css_gallery_item_title=&#8221;display: none;&#8221; box_shadow_horizontal_image_tablet=&#8221;0px&#8221; box_shadow_vertical_image_tablet=&#8221;0px&#8221; box_shadow_blur_image_tablet=&#8221;40px&#8221; box_shadow_spread_image_tablet=&#8221;0px&#8221; text_shadow_horizontal_length=&#8221;text_shadow_style,%91object Object%93&#8243; text_shadow_horizontal_length_tablet=&#8221;0px&#8221; text_shadow_vertical_length=&#8221;text_shadow_style,%91object Object%93&#8243; text_shadow_vertical_length_tablet=&#8221;0px&#8221; text_shadow_blur_strength=&#8221;text_shadow_style,%91object Object%93&#8243; text_shadow_blur_strength_tablet=&#8221;1px&#8221; title_text_shadow_horizontal_length=&#8221;title_text_shadow_style,%91object Object%93&#8243; title_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; title_text_shadow_vertical_length=&#8221;title_text_shadow_style,%91object Object%93&#8243; title_text_shadow_vertical_length_tablet=&#8221;0px&#8221; title_text_shadow_blur_strength=&#8221;title_text_shadow_style,%91object Object%93&#8243; title_text_shadow_blur_strength_tablet=&#8221;1px&#8221; caption_text_shadow_horizontal_length=&#8221;caption_text_shadow_style,%91object Object%93&#8243; caption_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; caption_text_shadow_vertical_length=&#8221;caption_text_shadow_style,%91object Object%93&#8243; caption_text_shadow_vertical_length_tablet=&#8221;0px&#8221; caption_text_shadow_blur_strength=&#8221;caption_text_shadow_style,%91object Object%93&#8243; caption_text_shadow_blur_strength_tablet=&#8221;1px&#8221; pagination_text_shadow_horizontal_length=&#8221;pagination_text_shadow_style,%91object Object%93&#8243; pagination_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; pagination_text_shadow_vertical_length=&#8221;pagination_text_shadow_style,%91object Object%93&#8243; pagination_text_shadow_vertical_length_tablet=&#8221;0px&#8221; pagination_text_shadow_blur_strength=&#8221;pagination_text_shadow_style,%91object Object%93&#8243; pagination_text_shadow_blur_strength_tablet=&#8221;1px&#8221; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; vertical_offset_tablet=&#8221;0&#8243; horizontal_offset_tablet=&#8221;0&#8243; z_index_tablet=&#8221;0&#8243; \/][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kampania muralowa Jeden z wielu murali w ramach kampani muralowej Nasze Maki adres: Boya-\u017bele\u0144skiego 72, Wroc\u0142aw<\/p>","protected":false},"author":3,"featured_media":8526,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[74],"tags":[105,231,135,353],"class_list":["post-8524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-murale-artystyczne","tag-mural","tag-nasze-maki","tag-wallart","tag-wroclaw"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>429. Nasze Maki - Murale<\/title>\n<meta name=\"description\" content=\"Mural we Wroc\u0142awiu w ramach kampani Nasze Maki\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wallart.pl\/fr\/429-peinture-murale-nos-coquelicots-a-wroclaw\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"429. Nasze Maki - Murale\" \/>\n<meta property=\"og:description\" content=\"Mural we Wroc\u0142awiu w ramach kampani Nasze Maki\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wallart.pl\/fr\/429-peinture-murale-nos-coquelicots-a-wroclaw\/\" \/>\n<meta property=\"og:site_name\" content=\"Murale Reklamowe i Artystyczne, Artystyczne Malowanie \u015acian | Wallart\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wallart.murale\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-02T16:16:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-10T20:02:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wallart.pl\/wp-content\/uploads\/2023\/09\/maki-wroclaw-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1965\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"wallart\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"wallart\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/\"},\"author\":{\"name\":\"wallart\",\"@id\":\"https:\/\/wallart.pl\/#\/schema\/person\/a5021cebb08301128dab13745299e4b3\"},\"headline\":\"429. Nasze Maki\",\"datePublished\":\"2023-09-02T16:16:11+00:00\",\"dateModified\":\"2025-01-10T20:02:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/\"},\"wordCount\":1899,\"publisher\":{\"@id\":\"https:\/\/wallart.pl\/#organization\"},\"image\":{\"@id\":\"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/wallart.pl\/wp-content\/uploads\/2023\/09\/maki-wroclaw-3.jpg\",\"keywords\":[\"mural\",\"nasze maki\",\"wallart\",\"wroc\u0142aw\"],\"articleSection\":[\"Artystyczne\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/\",\"url\":\"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/\",\"name\":\"429. Nasze Maki - Murale\",\"isPartOf\":{\"@id\":\"https:\/\/wallart.pl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/wallart.pl\/wp-content\/uploads\/2023\/09\/maki-wroclaw-3.jpg\",\"datePublished\":\"2023-09-02T16:16:11+00:00\",\"dateModified\":\"2025-01-10T20:02:59+00:00\",\"description\":\"Mural we Wroc\u0142awiu w ramach kampani Nasze Maki\",\"breadcrumb\":{\"@id\":\"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/#primaryimage\",\"url\":\"https:\/\/wallart.pl\/wp-content\/uploads\/2023\/09\/maki-wroclaw-3.jpg\",\"contentUrl\":\"https:\/\/wallart.pl\/wp-content\/uploads\/2023\/09\/maki-wroclaw-3.jpg\",\"width\":1800,\"height\":1965,\"caption\":\"mural Nasze Maki\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\/\/wallart.pl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"429. Nasze Maki\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wallart.pl\/#website\",\"url\":\"https:\/\/wallart.pl\/\",\"name\":\"Murale artystyczne i reklamowe \u2013 Wallart | Ca\u0142a Polska\",\"description\":\"Projektujemy i wykonujemy murale artystyczne, reklamowe i 3D w ca\u0142ej Polsce. Ponad 20 lat do\u015bwiadczenia, ponad 1000 realizacji \u2013 sprawd\u017a portfolio Wallart\",\"publisher\":{\"@id\":\"https:\/\/wallart.pl\/#organization\"},\"alternateName\":\"Wallart\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wallart.pl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/wallart.pl\/#organization\",\"name\":\"Wallart sp. z o.o.\",\"alternateName\":\"Wallart\",\"url\":\"https:\/\/wallart.pl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/wallart.pl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/wallart.pl\/wp-content\/uploads\/2023\/08\/LOGO-ikona-s.png\",\"contentUrl\":\"https:\/\/wallart.pl\/wp-content\/uploads\/2023\/08\/LOGO-ikona-s.png\",\"width\":800,\"height\":798,\"caption\":\"Wallart sp. z o.o.\"},\"image\":{\"@id\":\"https:\/\/wallart.pl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wallart.murale\",\"https:\/\/www.instagram.com\/wallart_mural\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/wallart.pl\/#\/schema\/person\/a5021cebb08301128dab13745299e4b3\",\"name\":\"wallart\",\"url\":\"https:\/\/wallart.pl\/fr\/author\/wallart\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"429 Nos coquelicots - Peintures murales","description":"Peinture murale \u00e0 Wroc\u0142aw dans le cadre de la campagne \"Our Poppies\" (Nos coquelicots)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wallart.pl\/fr\/429-peinture-murale-nos-coquelicots-a-wroclaw\/","og_locale":"fr_FR","og_type":"article","og_title":"429. Nasze Maki - Murale","og_description":"Mural we Wroc\u0142awiu w ramach kampani Nasze Maki","og_url":"https:\/\/wallart.pl\/fr\/429-peinture-murale-nos-coquelicots-a-wroclaw\/","og_site_name":"Murale Reklamowe i Artystyczne, Artystyczne Malowanie \u015acian | Wallart","article_publisher":"https:\/\/www.facebook.com\/wallart.murale","article_published_time":"2023-09-02T16:16:11+00:00","article_modified_time":"2025-01-10T20:02:59+00:00","og_image":[{"width":1800,"height":1965,"url":"https:\/\/wallart.pl\/wp-content\/uploads\/2023\/09\/maki-wroclaw-3.jpg","type":"image\/jpeg"}],"author":"wallart","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"wallart","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/#article","isPartOf":{"@id":"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/"},"author":{"name":"wallart","@id":"https:\/\/wallart.pl\/#\/schema\/person\/a5021cebb08301128dab13745299e4b3"},"headline":"429. Nasze Maki","datePublished":"2023-09-02T16:16:11+00:00","dateModified":"2025-01-10T20:02:59+00:00","mainEntityOfPage":{"@id":"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/"},"wordCount":1899,"publisher":{"@id":"https:\/\/wallart.pl\/#organization"},"image":{"@id":"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/#primaryimage"},"thumbnailUrl":"https:\/\/wallart.pl\/wp-content\/uploads\/2023\/09\/maki-wroclaw-3.jpg","keywords":["mural","nasze maki","wallart","wroc\u0142aw"],"articleSection":["Artystyczne"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/","url":"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/","name":"429 Nos coquelicots - Peintures murales","isPartOf":{"@id":"https:\/\/wallart.pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/#primaryimage"},"image":{"@id":"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/#primaryimage"},"thumbnailUrl":"https:\/\/wallart.pl\/wp-content\/uploads\/2023\/09\/maki-wroclaw-3.jpg","datePublished":"2023-09-02T16:16:11+00:00","dateModified":"2025-01-10T20:02:59+00:00","description":"Peinture murale \u00e0 Wroc\u0142aw dans le cadre de la campagne \"Our Poppies\" (Nos coquelicots)","breadcrumb":{"@id":"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/#primaryimage","url":"https:\/\/wallart.pl\/wp-content\/uploads\/2023\/09\/maki-wroclaw-3.jpg","contentUrl":"https:\/\/wallart.pl\/wp-content\/uploads\/2023\/09\/maki-wroclaw-3.jpg","width":1800,"height":1965,"caption":"mural Nasze Maki"},{"@type":"BreadcrumbList","@id":"https:\/\/wallart.pl\/429-nasze-maki-mural-we-wroclawiu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/wallart.pl\/"},{"@type":"ListItem","position":2,"name":"429. Nasze Maki"}]},{"@type":"WebSite","@id":"https:\/\/wallart.pl\/#website","url":"https:\/\/wallart.pl\/","name":"Peintures murales artistiques et publicitaires - Wallart | Toute la Pologne","description":"Projektujemy i wykonujemy murale artystyczne, reklamowe i 3D w ca\u0142ej Polsce. Ponad 20 lat do\u015bwiadczenia, ponad 1000 realizacji \u2013 sprawd\u017a portfolio Wallart","publisher":{"@id":"https:\/\/wallart.pl\/#organization"},"alternateName":"Wallart","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wallart.pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wallart.pl\/#organization","name":"Wallart sp. z o.o.","alternateName":"Wallart","url":"https:\/\/wallart.pl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wallart.pl\/#\/schema\/logo\/image\/","url":"https:\/\/wallart.pl\/wp-content\/uploads\/2023\/08\/LOGO-ikona-s.png","contentUrl":"https:\/\/wallart.pl\/wp-content\/uploads\/2023\/08\/LOGO-ikona-s.png","width":800,"height":798,"caption":"Wallart sp. z o.o."},"image":{"@id":"https:\/\/wallart.pl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wallart.murale","https:\/\/www.instagram.com\/wallart_mural\/"]},{"@type":"Person","@id":"https:\/\/wallart.pl\/#\/schema\/person\/a5021cebb08301128dab13745299e4b3","name":"art pari\u00e9tal","url":"https:\/\/wallart.pl\/fr\/author\/wallart\/"}]}},"_links":{"self":[{"href":"https:\/\/wallart.pl\/fr\/wp-json\/wp\/v2\/posts\/8524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wallart.pl\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wallart.pl\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wallart.pl\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/wallart.pl\/fr\/wp-json\/wp\/v2\/comments?post=8524"}],"version-history":[{"count":0,"href":"https:\/\/wallart.pl\/fr\/wp-json\/wp\/v2\/posts\/8524\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wallart.pl\/fr\/wp-json\/wp\/v2\/media\/8526"}],"wp:attachment":[{"href":"https:\/\/wallart.pl\/fr\/wp-json\/wp\/v2\/media?parent=8524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wallart.pl\/fr\/wp-json\/wp\/v2\/categories?post=8524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wallart.pl\/fr\/wp-json\/wp\/v2\/tags?post=8524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}